{"id":717,"date":"2015-12-18T21:03:59","date_gmt":"2015-12-18T20:03:59","guid":{"rendered":"http:\/\/www.vrabek.de\/design\/?p=717"},"modified":"2015-12-18T21:47:32","modified_gmt":"2015-12-18T20:47:32","slug":"befaehigung-zum-kriterium-der-vorinformiertheit-bezueglich-der-standardisierten-logik","status":"publish","type":"post","link":"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/befaehigung-zum-kriterium-der-vorinformiertheit-bezueglich-der-standardisierten-logik\/","title":{"rendered":"Bef\u00e4higung > Zum Kriterium der \u00bbVorinformiertheit\u00ab bez\u00fcglich der standardisierten Logik"},"content":{"rendered":"<p><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" style=\"margin:0 0 -8px 0\" width=\"60px\" height=\"30px\"><image xlink:href=\"http:\/\/www.vrabek.de\/design\/wp-content\/uploads\/2015\/12\/i_innovativ-1.svg\" src=\"\" width=\"60px\" height=\"30px\" alt=\"innovatives Potential\"  \/><\/svg> Zum Subprozess der Bef\u00e4higung in Relation zu Medien mit standardisierter Logik geh\u00f6rt es, sich das entsprechende Wissen, das zur Interaktion mit diesen Medien notwendig ist, anzueignen. Je komplexer dieses Wissen ist, desto schwieriger wird es f\u00fcr Nichtfachleute sich am Prozess der Nutzung oder Reaktivation zu beteiligen und umso h\u00e4rter und unver\u00e4nderbarer werden die Bedingungen, die durch Medien mit standardisierter Logik f\u00fcr ihre Erfahrung vorgegeben sind. Der bedingende Einfluss auf die Erfahrung im Subprozess der Bef\u00e4higung ist daher durch das Kriterium der Vorinformiertheit zu untersuchen und zu bewertet. Ein gewisses Ma\u00df an Vorinformation ist hinsichtlich jeder Interaktion mit standardisierten Medien unvermeidlich. Doch ist es keinem Laien zuzumuten, sich zur Nutzung dieser Medien das gesamte Fachwissen anzueignen. Dem Kriterium der Vorinformiertheit entsprechend muss die Komplexit\u00e4t des notwendigen Wissens daher auf ein vertretbares Ma\u00df komprimiert oder umgeformt werden. Hierbei kommt das innovative Potential von Design zum Einsatz.<\/p>\n<p>Die \u00e4sthetische Erfahrung w\u00e4hrend einer Interaktion bez\u00fcglich einem Medium mit standardisierter Logik wird durch das innovative Potential von Design verbessert, indem der n\u00f6tige Grad der Vorinformation abgesenkt wird, ohne das Endresultat zu stark zu beeintr\u00e4chtigen. Diese Erleichterung der Erfahrungsbedingungen im Subprozess der Bef\u00e4higung nach dem Kriterium der Vorinformiertheit kann im wesentlichen durch die Kombination von neuen mit bereits etablierten und bekannten Standards erreicht werden.<\/p>\n<h2>Beispiel f\u00fcr das innovative Potential von Design<\/h2>\n<p>Die Programmiersprache HTML (Hypertext Markup Language) zur Erstellung von Websites ist ein Medium mit standardisierter Logik. Beim Umgang mit ihm sind die Programmiervorschriften genau zu beachten. Hierin sind Informatiker ge\u00fcbt, aber nicht die vielen anderen Menschen, die gerne eine Website anlegen w\u00fcrden. Diese m\u00fcssten zun\u00e4chst den Grad ihrer Vorinformiertheit erh\u00f6hen, um das Medium aktiv nutzen zu k\u00f6nnen. Den Aufwand hierf\u00fcr k\u00f6nnten die meisten Interessierten nicht betreiben und w\u00e4ren somit von der mitgestaltenden Nutzung des Mediums Internet ausgeschlossen. Hier kann das innovative Potential von Design ansetzen. Aus der Kombination von HTML mit anderen Programmierstandards k\u00f6nnen Programme entwickelt werden, die bereits etablierten Softwarestandards entsprechen. Einerseits erleichtert deren gewohnte Bedienung einem Informatiklaien die Erstellung einer Website, andererseits entstehen aus der Kombination der verschiedenen Programmierstandards vielleicht neue M\u00f6glichkeiten. Diese Kombination von standardisierten Logiken und die daraus im anschlie\u00dfenden Interaktionsprozess hervorgehenden Innovationen tragen zur Verbesserung und Erweiterung der \u00e4sthetischen Erfahrung des Nutzers bei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zum Subprozess der Bef\u00e4higung in Relation zu Medien mit standardisierter Logik geh\u00f6rt es, sich das entsprechende Wissen, das zur Interaktion mit diesen Medien notwendig ist, anzueignen. Je komplexer dieses Wissen ist, desto schwieriger wird es f\u00fcr Nichtfachleute sich am Prozess&hellip;  <\/p>\n<p class=\"more-link\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/befaehigung-zum-kriterium-der-vorinformiertheit-bezueglich-der-standardisierten-logik\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":456,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,20],"tags":[],"_links":{"self":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/717"}],"collection":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/comments?post=717"}],"version-history":[{"count":2,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/717\/revisions"}],"predecessor-version":[{"id":739,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/717\/revisions\/739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/media\/456"}],"wp:attachment":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/media?parent=717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/categories?post=717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/tags?post=717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}