{"id":697,"date":"2015-12-18T20:35:51","date_gmt":"2015-12-18T19:35:51","guid":{"rendered":"http:\/\/www.vrabek.de\/design\/?p=697"},"modified":"2015-12-18T21:43:59","modified_gmt":"2015-12-18T20:43:59","slug":"verfuegung-zum-kriterium-der-vergegenwaertigbarkeit-bezueglich-der-organischen-logik","status":"publish","type":"post","link":"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/verfuegung-zum-kriterium-der-vergegenwaertigbarkeit-bezueglich-der-organischen-logik\/","title":{"rendered":"Verf\u00fcgung > Zum Kriterium der \u00bbVergegenw\u00e4rtigbarkeit\u00ab bez\u00fcglich der organischen Logik"},"content":{"rendered":"<p><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" style=\"margin:0 0 -8px 0\" width=\"60px\" height=\"30px\"><image xlink:href=\"http:\/\/www.vrabek.de\/design\/wp-content\/uploads\/2015\/12\/i_adaptiv.svg\" src=\"\" width=\"60px\" height=\"30px\" alt=\"adaptives Potential\"  \/><\/svg> Hinsichtlich der Interaktion mit Medien, die der organischen Logik folgen, ist zu beachten, dass die F\u00e4higkeit hierzu besonders stark von der Vorgeschichte einer Person und dem durch Verk\u00f6rperung manifestierten Erfahrungswissen abh\u00e4ngt. So steht vielen Menschen das Fahrradfahren im Prinzip zur Verf\u00fcgung, da sie jederzeit ein Rad besteigen und losfahren k\u00f6nnten, allerdings w\u00e4re es sicher f\u00fcr einen Gro\u00dfteil problematisch, eine vorgegebene Wegef\u00fchrung mit einigen Schwierigkeitsgraden abzufahren. Auch das Aufsagen einer kurzen Gru\u00dfformel w\u00e4re f\u00fcr die meisten Menschen eine einfache Aufgabe, wogegen es ihnen schwer fiele, eine kleine, freie Begr\u00fc\u00dfungsrede zu halten. Die Reaktivation von geistigen oder k\u00f6rperlichen Erfahrungen im Umgang mit vorrangig durch die organische Logik gepr\u00e4gten Medien, basiert auf der Vergegenw\u00e4rtigbarkeit des einmal gelernten.<\/p>\n<p>Allein diese im Subprozess der Verf\u00fcgung vergegenw\u00e4rtigbaren Erfahrungen stehen zur Reaktivation bereit. Die bedingende Wirkung auf die Erfahrung w\u00e4hrend dem Subprozess der Verf\u00fcgung ist daher durch das Kriterium der Vergegenw\u00e4rtigbarkeit zu kennzeichnen. Zum einen ger\u00e4t dasjenige, was nur oberfl\u00e4chlich gelernt wurde rasch in Vergessenheit. Zum anderen tr\u00e4gt mangelnde Reaktivierung des Gelernten zum Vergessen bei. So k\u00f6nnen viele Erwachsene ihre Fremdsprachenkenntnisse nicht reaktivieren, weil sie diese Sprache in der Schulzeit nur in wenigen Unterrichtsstunden lernten und selten in der Lebenspraxis zur Anwendung bringen konnten. Auch das Wissen aus anderen Wissensgebieten, deren Kennenlernen sich allein auf die Schulstunden beschr\u00e4nkte, ist nach der Schulzeit nur noch von wenigen Menschen zu vergegenw\u00e4rtigen.<\/p>\n<p>Der \u00dcbergang von der Industrie- zur Wissensgesellschaft ist nur von Menschen zu vollziehen, die bereit sind, lebenslang zu lernen, denn Wissen wird nicht mehr als ein f\u00fcr allemal feststehend modelliert. Hierbei kann das adaptive Potential von Design verst\u00e4rkt zum Einsatz kommen. Dem Kriterium der Vergegenw\u00e4rtigbarkeit ist beispielsweise zu entsprechen, indem die didaktische und dramaturgische Aufbereitung von Lernstoffen in nach Schwierigkeitsgraden gestaffelter Form erfolgt. Auf diese Weise ist zun\u00e4chst ein oberfl\u00e4chlicher \u00dcberblick zu vermitteln und anschlie\u00dfend das gezielte, tiefergehende Lernen auf die individuellen Erfordernisse des Lernenden abzustimmen.<\/p>\n<h2>Beispiel f\u00fcr das adaptive Potential von Design<\/h2>\n<p>Einfache und somit leichter vergegenw\u00e4rtigbare Erfahrungsanteile zu einem Wissensgebiet k\u00f6nnen als Einstiegshilfen angeboten werden, um sich an das bereits Gelernte besser zu erinnern sowie darauf aufbauen oder ankn\u00fcpfen zu k\u00f6nnen. Einige Lern- und Hilfsprogramme f\u00fcr Computersoftware begleiten den Nutzer bereits in diesem Sinne. Das Aufgabenfeld der didaktischen Aufbereitung von Wissensstoffen unter Anwendung der Multimedia-Technologie, erfordert die st\u00e4rkere Beteiligung von Designern und wird bez\u00fcglich dem Computer-Based-Training f\u00fcr die Aus- und Weiterbildung weiter wachsen.<\/p>\n<p>Die Zertifizierung im Bereich der Weiterbildung stellt nicht mehr das durch eine Pr\u00fcfung in Form eines \u00bbVerh\u00f6rs\u00ab abrufbare Wissen als vorbildlich hervor, sondern zeichnet solche Kenntnisse aus, die im Zusammenhang mit einem praktischen Szenario vergegenw\u00e4rtigt werden k\u00f6nnen. Auch die Erwartungen von Arbeitgebern gehen in diese Richtung. Diese legen weniger Wert auf traditionelle Pr\u00fcfzeugnisse, als vielmehr auf den Nachweis von verf\u00fcgbarem, vergegenw\u00e4rtigbarem Wissen bez\u00fcglich der Praxis. Somit ist auch die Form der Pr\u00fcfung entsprechend umzugestalten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hinsichtlich der Interaktion mit Medien, die der organischen Logik folgen, ist zu beachten, dass die F\u00e4higkeit hierzu besonders stark von der Vorgeschichte einer Person und dem durch Verk\u00f6rperung manifestierten Erfahrungswissen abh\u00e4ngt. So steht vielen Menschen das Fahrradfahren im Prinzip zur&hellip;  <\/p>\n<p class=\"more-link\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/verfuegung-zum-kriterium-der-vergegenwaertigbarkeit-bezueglich-der-organischen-logik\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":429,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/697"}],"collection":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/comments?post=697"}],"version-history":[{"count":2,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/697\/revisions"}],"predecessor-version":[{"id":734,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/697\/revisions\/734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/media\/429"}],"wp:attachment":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/media?parent=697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/categories?post=697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/tags?post=697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}