{"id":684,"date":"2015-12-18T19:55:17","date_gmt":"2015-12-18T18:55:17","guid":{"rendered":"http:\/\/www.vrabek.de\/design\/?p=684"},"modified":"2015-12-18T21:45:08","modified_gmt":"2015-12-18T20:45:08","slug":"verbreitung-zum-kriterium-des-darstellbarkeit-bezueglich-der-organischen-logik","status":"publish","type":"post","link":"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/verbreitung-zum-kriterium-des-darstellbarkeit-bezueglich-der-organischen-logik\/","title":{"rendered":"Verbreitung > Zum Kriterium des \u00bbDarstellbarkeit\u00ab bez\u00fcglich der organischen Logik"},"content":{"rendered":"<p><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" style=\"margin:0 0 -8px 0\" width=\"60px\" height=\"30px\"><image xlink:href=\"http:\/\/www.vrabek.de\/design\/wp-content\/uploads\/2015\/12\/i_adaptiv.svg\" src=\"\" width=\"60px\" height=\"30px\" alt=\"adaptives Potential\"  \/><\/svg> Solange ein Individuum vorwiegend seine organischen Medien f\u00fcr die Interaktion mit der Welt nutzt, bleibt deren Entfaltung f\u00fcr die Erfahrung im Prinzip auf das subjektive Erleben begrenzt. Ein im Spiel versunkenes Kind ist in seinem Tun aufgehoben. Es will damit nichts mitteilen, denkt nicht an au\u00dfenstehende Beobachter oder an ein fertiges Produkt als Resultat seines Spiels. Es lebt voll und ganz ohne zeitliche oder r\u00e4umliche Beschr\u00e4nkungen zu bemerken im Spielen, bis Hunger oder M\u00fcdigkeit aufkommt. Au\u00dfer dem Kind selbst hat keiner erfahren, worum es bei diesem Spielen ging. Das Ergebnis dieser T\u00e4tigkeit ist, abgesehen von vielleicht zur\u00fcckbleibenden Spuren, nur als Ver\u00e4nderung der verk\u00f6rperten Kompetenzen des Kindes im Umgang mit den organischen Medien zu beobachten, es ist nicht als solches darstellbar. Ebenso k\u00f6nnen durch Variieren und Trainieren mittels organischer Medien erzeugte Erfahrungen, seien dies k\u00f6rperliche Fitness oder Phantasiewelten, f\u00fcr andere Menschen verborgen bleiben. In der Schachnovelle von Siegfried Lenz lernt die in Einzelhaft eingesperrte Hauptfigur das Schachspielen aus einem Buch. Sie muss alle Indizien von Spielversuchen wie Brotkr\u00fcmel als Spielsteine, Kratzspuren als Spielfelder usw. vor den Bewachern verstecken und spielt schlie\u00dflich nur noch im Gedanken. Der Gefangene erreicht ein Niveau, auf dem er simultan mehrere Spiele im Kopf sozusagen gegen sich selbst spielen kann. Sp\u00e4ter, wieder in Freiheit, ergibt sich erstmals die Gelegenheit zu einem realen Schachspiel. Er kann es nicht zu Ende f\u00fchren, weil er unf\u00e4hig ist, sich auf das Spieltempo seines realen Gegners einzustellen. So ist seine Kompetenz des Schachspielens zwar durch Verk\u00f6rperung fixiert, er kann sie aber nur f\u00fcr sich alleine aus\u00fcben. Das Kriterium der Darstellbarkeit, das f\u00fcr eine Vervielf\u00e4ltigung seiner Kompetenz n\u00f6tig w\u00e4re, damit andere seine Spielz\u00fcge wenigstens durch Abschauen lernen k\u00f6nnten, ist bei ihm nicht erf\u00fcllt.<\/p>\n<p>Das adaptive Potential von Design ist daf\u00fcr einzusetzen, die Darstellbarkeit verk\u00f6rperter Erfahrungen zu erleichtern, indem unterschiedliche Darstellungsarten bereitgestellt werden. Dies ist insbesondere im schulischen Bereich wichtig. Einerseits bekommen Sch\u00fcler, denen es nicht gelingt, ihre Kompetenzen zur Darstellung zu bringen, diese allzu leicht v\u00f6llig abgesprochen. Andererseits m\u00fcssen Lehrer in ihren Unterricht dem Kriterium der Darstellbarkeit entsprechend gestalten, und ihr verk\u00f6rpertes Wissen f\u00fcr die Verbreitung aufbereiten.<\/p>\n<h2>Beispiel f\u00fcr das adaptive Potential von Design<\/h2>\n<p>Mit traditioneller Ausbildung entwickeln sich geh\u00f6rlose Kinder langsamer als zur Verbalsprache bef\u00e4higte Kinder. Zudem haben es schwerer, ihrer F\u00e4higkeiten darzustellen. In Schulversuchen mit der Geb\u00e4rdensprache als Hauptsprache tritt die normale Intelligenz der Geh\u00f6rlosen zu Tage. Das adaptive Potential der Geb\u00e4rdensprache erm\u00f6glicht es ihnen, ihre verk\u00f6rperten F\u00e4higkeiten darzustellen.<\/p>\n<p>Menschen unterscheiden sich durch die Bevorzugung von bestimmten Darstellungsmodalit\u00e4ten bez\u00fcglich der Produktion und auch der Rezeption (vgl. Vester, 1978; Markova, 1993). Das adaptive Potential von Design kann dieser Tatsache durch entsprechend vorbereitetes Unterrichtsmaterial Rechnung tragen indem nicht allein die verbale Sprache als prim\u00e4res Darstellungsmedium zugelassen wird. Die Sprachf\u00e4higkeit vieler Kinder ist bis zur Pubert\u00e4t durch Legasthenie eingeschr\u00e4nkt. Gerade diese Kinder k\u00f6nnen sich sehr gut durch visuelle Medien, Musik oder K\u00f6rperbewegungen ausdr\u00fccken. Durch den Einsatz von Computerprogrammen, die nach dem Kriterium der Darstellbarkeit konzipiert sind und multimodale Darstellungsweisen wie T\u00f6ne, Farben, Formen und Animationen anbieten, wird es f\u00fcr viele Kinder leichter, sowohl ihre besonderen F\u00e4higkeiten zu pr\u00e4sentieren, als auch den Lernstoff besser in ihre Erfahrungswirklichkeit zu integrieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solange ein Individuum vorwiegend seine organischen Medien f\u00fcr die Interaktion mit der Welt nutzt, bleibt deren Entfaltung f\u00fcr die Erfahrung im Prinzip auf das subjektive Erleben begrenzt. Ein im Spiel versunkenes Kind ist in seinem Tun aufgehoben. Es will damit&hellip;  <\/p>\n<p class=\"more-link\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/verbreitung-zum-kriterium-des-darstellbarkeit-bezueglich-der-organischen-logik\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":429,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/684"}],"collection":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/comments?post=684"}],"version-history":[{"count":2,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/684\/revisions"}],"predecessor-version":[{"id":736,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/posts\/684\/revisions\/736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/media\/429"}],"wp:attachment":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/media?parent=684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/categories?post=684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/tags?post=684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}