{"id":147,"date":"2015-12-01T23:40:43","date_gmt":"2015-12-01T22:40:43","guid":{"rendered":"http:\/\/www.vrabek.de\/design\/?page_id=147"},"modified":"2015-12-18T21:04:57","modified_gmt":"2015-12-18T20:04:57","slug":"5-3-3-2-kriterien-zum-subprozess-der-befaehigung","status":"publish","type":"page","link":"https:\/\/www.vrabek.de\/design\/5-mediales\/5-3-3-subprozesse-im-teilprozess-der-reaktivation\/5-3-3-2-kriterien-zum-subprozess-der-befaehigung\/","title":{"rendered":"5.3.3.2 Kriterien zum Subprozess der Bef\u00e4higung"},"content":{"rendered":"<p>Aus dem Subprozess der Bef\u00e4higung sind solche Kriterien f\u00fcr die Erfahrung ableitbar, die damit zusammenh\u00e4ngen, dass ein Medium zwar zur Verf\u00fcgung bereit steht, ein Nutzer jedoch nicht dazu bef\u00e4higt ist, mit diesem zu interagieren. In Relation zu Medien mit organischer Logik l\u00e4sst sich diese Bedingung mit dem Kriterium der Vollzugsf\u00e4higkeit erfassen. Hinsichtlich der Medien mit organischer Logik ist das Kriterium der Vollzugsf\u00e4higkeit und bez\u00fcglich der Medien mit standardisierter Logik das Kriterium der Vorinformiertheit zu untersuchen.<\/p>\n<h2 class=\"cprp_section_title\">:: Mehr zum Thema ::<\/h2><div class=\"cprp_items list \"><ul><li><div class=\"cprp_data\"><div class=\"cprp_title\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/befaehigung-zum-kriterium-der-vollzugsfaehigkeit-bezueglich-der-organischen-logik\/\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVollzugsf\u00e4higkeit\u00ab bez\u00fcglich der organischen Logik\">Bef\u00e4higung > Zum Kriterium der \u00bbVollzugsf\u00e4higkeit\u00ab bez\u00fcglich der organischen Logik<\/a><\/div><div class=\"cprp_excerpt\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/befaehigung-zum-kriterium-der-vollzugsfaehigkeit-bezueglich-der-organischen-logik\/\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVollzugsf\u00e4higkeit\u00ab bez\u00fcglich der organischen Logik\"><img src=\"https:\/\/www.vrabek.de\/design\/wp-content\/uploads\/2015\/12\/i_adaptiv.svg\" class=\"cprp_thumbnail\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVollzugsf\u00e4higkeit\u00ab bez\u00fcglich der organischen Logik\" alt=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVollzugsf\u00e4higkeit\u00ab bez\u00fcglich der organischen Logik\" \/><\/a><span class=\"cprp_excerpt_content\">Die Verf\u00fcgung \u00fcber bestimmte organische Medien kann zwar gegeben sein, trotzdem steht der Subproze\u00df der Bef\u00e4higung noch vor dem Subproze\u00df der endg\u00fcltigen Ausf\u00fchrung, denn ohne Ber\u00fccksichtigung des Kriteriums der Vollzugsf\u00e4higkeit kann der Teilprozess der Reaktivation nicht abschlie\u00dfbar sind. Zeichnen als Medium mit organischer Logik erfordert nicht nur die vergegenw\u00e4rtigende Verf\u00fcgung&hellip;<\/span><\/div><div class=\"cprp_tags\">Tags: vollzugsf\u00e4higkeit, medien, kriterium, logik, bez\u00fcglich, medium, organischer, erfahrung<\/div><\/div><\/li><li><div class=\"cprp_data\"><div class=\"cprp_title\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/befaehigung-zum-kriterium-der-verbindlichkeit-bezueglich-der-kontextuellen-logik\/\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVerbindlichkeit\u00ab bez\u00fcglich der kontextuellen Logik\">Bef\u00e4higung > Zum Kriterium der \u00bbVerbindlichkeit\u00ab bez\u00fcglich der kontextuellen Logik<\/a><\/div><div class=\"cprp_excerpt\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/befaehigung-zum-kriterium-der-verbindlichkeit-bezueglich-der-kontextuellen-logik\/\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVerbindlichkeit\u00ab bez\u00fcglich der kontextuellen Logik\"><img src=\"https:\/\/www.vrabek.de\/design\/wp-content\/uploads\/2015\/12\/i_situativ.svg\" class=\"cprp_thumbnail\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVerbindlichkeit\u00ab bez\u00fcglich der kontextuellen Logik\" alt=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVerbindlichkeit\u00ab bez\u00fcglich der kontextuellen Logik\" \/><\/a><span class=\"cprp_excerpt_content\">Im Unterschied zur Interaktion mit organischen Medien, deren Registrierung manchmal nur vom subjektiven Beobachterstandpunkt aus, im innerlich geschlossenen Raum erfolgt, beinhaltet das Interagieren mit kontextuellen Medien eine \u00d6ffnung nach au\u00dfen. Erst dadurch kann jedes Individuum aktiv seine Erfahrungen in den Lebenskontext einbringen. Der Prozess der Reaktivation bez\u00fcglich des Umgehens mit&hellip;<\/span><\/div><div class=\"cprp_tags\">Tags: f\u00fcr, medien, bez\u00fcglich, kriterium, logik, bef\u00e4higung, diesem, erfahrung<\/div><\/div><\/li><li><div class=\"cprp_data\"><div class=\"cprp_title\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/befaehigung-zum-kriterium-der-vorinformiertheit-bezueglich-der-standardisierten-logik\/\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVorinformiertheit\u00ab bez\u00fcglich der standardisierten Logik\">Bef\u00e4higung > Zum Kriterium der \u00bbVorinformiertheit\u00ab bez\u00fcglich der standardisierten Logik<\/a><\/div><div class=\"cprp_excerpt\"><a href=\"https:\/\/www.vrabek.de\/design\/2015\/12\/18\/befaehigung-zum-kriterium-der-vorinformiertheit-bezueglich-der-standardisierten-logik\/\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVorinformiertheit\u00ab bez\u00fcglich der standardisierten Logik\"><img src=\"https:\/\/www.vrabek.de\/design\/wp-content\/uploads\/2015\/12\/i_innovativ-1.svg\" class=\"cprp_thumbnail\" title=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVorinformiertheit\u00ab bez\u00fcglich der standardisierten Logik\" alt=\"Bef\u00e4higung &gt; Zum Kriterium der \u00bbVorinformiertheit\u00ab bez\u00fcglich der standardisierten Logik\" \/><\/a><span class=\"cprp_excerpt_content\">Zum Subprozess der Bef\u00e4higung in Relation zu Medien mit standardisierter Logik geh\u00f6rt es, sich das entsprechende Wissen, das zur Interaktion mit diesen Medien notwendig ist, anzueignen. Je komplexer dieses Wissen ist, desto schwieriger wird es f\u00fcr Nichtfachleute sich am Prozess der Nutzung oder Reaktivation zu beteiligen und umso h\u00e4rter und&hellip;<\/span><\/div><div class=\"cprp_tags\">Tags: vorinformiertheit, logik, medien, standardisierter, erfahrung, bef\u00e4higung, kriterium, f\u00fcr, diese, medium<\/div><\/div><\/li><\/ul><\/div><div style=\"clear:both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Aus dem Subprozess der Bef\u00e4higung sind solche Kriterien f\u00fcr die Erfahrung ableitbar, die damit zusammenh\u00e4ngen, dass ein Medium zwar zur Verf\u00fcgung bereit steht, ein Nutzer jedoch nicht dazu bef\u00e4higt ist, mit diesem zu interagieren. In Relation zu Medien mit organischer&hellip;  <\/p>\n<p class=\"more-link\"><a href=\"https:\/\/www.vrabek.de\/design\/5-mediales\/5-3-3-subprozesse-im-teilprozess-der-reaktivation\/5-3-3-2-kriterien-zum-subprozess-der-befaehigung\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":143,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/pages\/147"}],"collection":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/comments?post=147"}],"version-history":[{"count":2,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/pages\/147\/revisions"}],"predecessor-version":[{"id":586,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/pages\/147\/revisions\/586"}],"up":[{"embeddable":true,"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/pages\/143"}],"wp:attachment":[{"href":"https:\/\/www.vrabek.de\/design\/wp-json\/wp\/v2\/media?parent=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}